{"id":78,"count":10,"description":"","link":"https:\/\/psdev2.com\/blog\/tag\/facebook-newsfeed","name":"Facebook Newsfeed","slug":"facebook-newsfeed","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/psdev2.com\/blog\/wp-json\/wp\/v2\/tags\/78"}],"collection":[{"href":"https:\/\/psdev2.com\/blog\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/psdev2.com\/blog\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/psdev2.com\/blog\/wp-json\/wp\/v2\/posts?tags=78"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}